{"id":115,"date":"2014-02-19T00:29:28","date_gmt":"2014-02-19T00:29:28","guid":{"rendered":"http:\/\/fundacionpuertocolombia.org\/?page_id=115"},"modified":"2014-08-02T16:59:56","modified_gmt":"2014-08-02T16:59:56","slug":"historia","status":"publish","type":"page","link":"https:\/\/fundacionpuertocolombia.org\/en\/puerto-colombia\/historia\/","title":{"rendered":"Historia"},"content":{"rendered":"<p style=\"text-align: justify;\"><b>Puerto Colombia<\/b>\u00a0es una poblaci\u00f3n y municipio\u00a0de colombia\u00a0ubicado al noroccidente del Dpto. del Atl\u00e1ntico. Colinda al norte con las costas del mar caribe. Entre fines del siglo XIX y la primera mitad del XX funcion\u00f3 como terminal mar\u00edtimo de Barranquilla, con la cual se conectaba v\u00eda f\u00e9rrea. Su c\u00e9lebre muelle\u00a0fue dise\u00f1ado por el ingeniero cubano Francisco Javier Cisneros e inaugurado en 1893.<\/p>\n<p style=\"text-align: justify;\">El territorio ocupado actualmente por el municipio de Puerto Colombia form\u00f3 parte jur\u00eddicamente del municipio de Tubar\u00e1, territorio ocupado tradicionalmente por la cultura Mocana. Su origen data del a\u00f1o de 1850 cuando un n\u00famero significativo de familias originarias de Tubar\u00e1 y San Antonio de Salgar levantaron sus viviendas al pie de un cerro llamado Cupino, del cual deriv\u00f3 su nombre, cerro de Cupino, atra\u00eddos por la abundancia de pesca y la tranquilidad del medio.<\/p>\n<p style=\"text-align: justify;\">El 31 de diciembre de 1870 se inaugur\u00f3 el ferrocarril de Barranquilla a Salgar. A causa del poco fondo de la bah\u00eda, se decidi\u00f3, a instancias de Cisneros, quien hab\u00eda adquirido el ferrocarril, la prolongaci\u00f3n de la l\u00ednea f\u00e9rrea hasta Cupino, obra que se inaugur\u00f3 el 31 de diciembre de 1888.<a href=\"http:\/\/es.wikipedia.org\/wiki\/Puerto_Colombia#cite_note-lecturaslocales-2\"><br \/>\n<\/a><\/p>\n<p style=\"text-align: justify;\">Posteriormente el caser\u00edo tom\u00f3 el nombre de Puerto Colombia en 1893, cuando se concluyeron las obras de construcci\u00f3n del muelle a cargo del ingeniero cubano. Se dio paso al terminal mar\u00edtimo m\u00e1s importante de Colombia en las primeras cuatro d\u00e9cadas del siglo XX y a un municipio de permanente desarrollo, sirviendo de puerto a Barranquilla. Este muelle fue en su momento el segundo m\u00e1s largo del mundo, con 4.000 pies de longitud.<\/p>\n<p style=\"text-align: justify;\">El nombre se dio el d\u00eda de la inauguraci\u00f3n del muelle, 15 de agosto de 1893. Cisneros hab\u00eda propuesto al Presidente de la Rep\u00fablica de ese momento, Rafael Nu\u00f1ez, llamar a la localidad Puerto N\u00fa\u00f1ez; \u00e9l no acept\u00f3 y respondi\u00f3 que deb\u00eda llam\u00e1rsele Puerto Cisneros, a lo que el ingenioso empresario contest\u00f3 denomin\u00e1ndolo Puerto Colombia. Puerto Colombia fue elevado a la categor\u00eda de municipio por el Decreto 19 de 24 de junio de 1905, emanado del gobernador del departamento de Atl\u00e1ntico.<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 20%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-115 gallery-columns-5 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/muelleypersonas2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/muelleypersonas2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/muelleypersonas.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/muelleypersonas-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/muelle70.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/muelle70-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Muelle-de-Puerto-Colombia-Imagen.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Muelle-de-Puerto-Colombia-Imagen-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Muelle-de-Puerto-Colombia-Imagen-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Muelle-de-Puerto-Colombia-Imagen-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/inmigrantes-en-Puerto.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/inmigrantes-en-Puerto-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/estacion-ferrocarril-antigua.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/estacion-ferrocarril-antigua-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/estacion-ferrocarril-antigua-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/estacion-ferrocarril-antigua-2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/estacion-antigua2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/estacion-antigua2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/estacion-antigua.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/estacion-antigua-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/el-primer-avion.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/el-primer-avion-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Ellis-Island1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Ellis-Island1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/el-primer-avion1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/el-primer-avion1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Correo-Aereo.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Correo-Aereo-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Antigua-Alcaldia.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Antigua-Alcaldia-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/545434_432429403489806_627234089_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/545434_432429403489806_627234089_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/293064_10151125555617249_1775733158_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/293064_10151125555617249_1775733158_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108181597248_6769547_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108181597248_6769547_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108181602248_3073718_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108181602248_3073718_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/32285_420360127248_1609693_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/32285_420360127248_1609693_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/46265_432429420156471_2108408987_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/46265_432429420156471_2108408987_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108181592248_2981163_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108181592248_2981163_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108181587248_7408708_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108181587248_7408708_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108179547248_8286096_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108179547248_8286096_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108109897248_5719467_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/4840_108109897248_5719467_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Untitled6.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Untitled6-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Untitled4.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Untitled4-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Untitled3.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Untitled3-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Untitled.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Untitled-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/scluting.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/scluting-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/SSPAW.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/SSPAW-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Hamburg-American-Line.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Hamburg-American-Line-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Prinz-August.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Prinz-August-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/GermanScuttling.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/GermanScuttling-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/267601_10150227508111822_612761821_7554107_3702143_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/267601_10150227508111822_612761821_7554107_3702143_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/268457_10150224804346822_612761821_7523210_2361068_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/268457_10150224804346822_612761821_7523210_2361068_n-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/CORDILLERA.png'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/CORDILLERA-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/DSC05405.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/DSC05405-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Puerto Colombia\u00a0es una poblaci\u00f3n y municipio\u00a0de colombia\u00a0ubicado al noroccidente del Dpto. del Atl\u00e1ntico. Colinda al norte con las costas del\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/puerto-colombia\/historia\/\">Seguir Leyendo<\/a><\/p>","protected":false},"author":2,"featured_media":228,"parent":44,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-115","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Historia - Fundaci\u00f3n Puerto Colombia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/puerto-colombia\/historia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historia\" \/>\n<meta property=\"og:description\" content=\"Puerto Colombia\u00a0es una poblaci\u00f3n y municipio\u00a0de colombia\u00a0ubicado al noroccidente del Dpto. del Atl\u00e1ntico. Colinda al norte con las costas del\u2026 Seguir Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionpuertocolombia.org\/en\/puerto-colombia\/historia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Puerto Colombia\" \/>\n<meta property=\"article:modified_time\" content=\"2014-08-02T16:59:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Muelle-de-Puerto-Colombia-Imagen-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1700\" \/>\n\t<meta property=\"og:image:height\" content=\"2338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/puerto-colombia\\\/historia\\\/\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/puerto-colombia\\\/historia\\\/\",\"name\":\"Historia - Fundaci\u00f3n Puerto Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/puerto-colombia\\\/historia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/puerto-colombia\\\/historia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/Muelle-de-Puerto-Colombia-Imagen-1.jpg\",\"datePublished\":\"2014-02-19T00:29:28+00:00\",\"dateModified\":\"2014-08-02T16:59:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/puerto-colombia\\\/historia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionpuertocolombia.org\\\/puerto-colombia\\\/historia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/puerto-colombia\\\/historia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/Muelle-de-Puerto-Colombia-Imagen-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/Muelle-de-Puerto-Colombia-Imagen-1.jpg\",\"width\":1700,\"height\":2338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/puerto-colombia\\\/historia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puerto Colombia\",\"item\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/puerto-colombia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Historia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\",\"name\":\"Fundaci\u00f3n Puerto Colombia\",\"description\":\"Tierra Firme Para La Cultura!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Historia - Fundaci\u00f3n Puerto Colombia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionpuertocolombia.org\/en\/puerto-colombia\/historia\/","og_locale":"en_US","og_type":"article","og_title":"Historia","og_description":"Puerto Colombia\u00a0es una poblaci\u00f3n y municipio\u00a0de colombia\u00a0ubicado al noroccidente del Dpto. del Atl\u00e1ntico. Colinda al norte con las costas del\u2026 Seguir Leyendo","og_url":"https:\/\/fundacionpuertocolombia.org\/en\/puerto-colombia\/historia\/","og_site_name":"Fundaci\u00f3n Puerto Colombia","article_modified_time":"2014-08-02T16:59:56+00:00","og_image":[{"width":1700,"height":2338,"url":"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Muelle-de-Puerto-Colombia-Imagen-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fundacionpuertocolombia.org\/puerto-colombia\/historia\/","url":"https:\/\/fundacionpuertocolombia.org\/puerto-colombia\/historia\/","name":"Historia - Fundaci\u00f3n Puerto Colombia","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/puerto-colombia\/historia\/#primaryimage"},"image":{"@id":"https:\/\/fundacionpuertocolombia.org\/puerto-colombia\/historia\/#primaryimage"},"thumbnailUrl":"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Muelle-de-Puerto-Colombia-Imagen-1.jpg","datePublished":"2014-02-19T00:29:28+00:00","dateModified":"2014-08-02T16:59:56+00:00","breadcrumb":{"@id":"https:\/\/fundacionpuertocolombia.org\/puerto-colombia\/historia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionpuertocolombia.org\/puerto-colombia\/historia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fundacionpuertocolombia.org\/puerto-colombia\/historia\/#primaryimage","url":"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Muelle-de-Puerto-Colombia-Imagen-1.jpg","contentUrl":"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/02\/Muelle-de-Puerto-Colombia-Imagen-1.jpg","width":1700,"height":2338},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionpuertocolombia.org\/puerto-colombia\/historia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionpuertocolombia.org\/"},{"@type":"ListItem","position":2,"name":"Puerto Colombia","item":"https:\/\/fundacionpuertocolombia.org\/puerto-colombia\/"},{"@type":"ListItem","position":3,"name":"Historia"}]},{"@type":"WebSite","@id":"https:\/\/fundacionpuertocolombia.org\/#website","url":"https:\/\/fundacionpuertocolombia.org\/","name":"Fundaci\u00f3n Puerto Colombia","description":"Tierra Firme Para La Cultura!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionpuertocolombia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/pages\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/comments?post=115"}],"version-history":[{"count":0,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/pages\/115\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/pages\/44"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/media\/228"}],"wp:attachment":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/media?parent=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}