{"id":3456,"date":"2015-10-19T16:08:41","date_gmt":"2015-10-19T16:08:41","guid":{"rendered":"http:\/\/fundacionpuertocolombia.org\/?p=3456"},"modified":"2015-10-19T17:01:26","modified_gmt":"2015-10-19T17:01:26","slug":"ganador-concurso-internacional-cartel-de-la-paz","status":"publish","type":"post","link":"https:\/\/fundacionpuertocolombia.org\/en\/ganador-concurso-internacional-cartel-de-la-paz\/","title":{"rendered":"Ganador Concurso Internacional Cartel de la paz."},"content":{"rendered":"<div id=\"attachment_3459\" style=\"width: 896px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-3459\" class=\"wp-image-3459 size-full\" src=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962.jpg\" alt=\"Fotograf\u00eda: Diego Mari\u00f1o.\" width=\"886\" height=\"591\" srcset=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962.jpg 886w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962-300x200.jpg 300w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962-600x400.jpg 600w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962-225x150.jpg 225w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962-150x100.jpg 150w\" sizes=\"(max-width: 886px) 100vw, 886px\" \/><p id=\"caption-attachment-3459\" class=\"wp-caption-text\">Rep. del Club de Leones de Puerto Colombia, Coordinadora General Fundaci\u00f3n Puerto Colombia y Jurados del Concurso.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">El pasado viernes 16 de Octubre se celebr\u00f3 en las instalaciones de la Fundaci\u00f3n Puerto Colombia el Concurso Internacional Cartel de la paz, evento que se ha llevado a cabo durante varios a\u00f1os y en donde los club de leones de todas partes del mundo cumplen su cita para escoger a las y los \u00a0j\u00f3venes representantes de cada regi\u00f3n que participaran a nivel nacional e internacional por llevarse el puesto de GANADOR DEL CARTEL DE LA PAZ.<\/p>\n<div id=\"attachment_3460\" style=\"width: 210px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1968.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-3460\" class=\"wp-image-3460 size-medium\" src=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1968-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" \/><\/a><p id=\"caption-attachment-3460\" class=\"wp-caption-text\">Obra ganadora. La primera de derecha a izquierda<\/p><\/div>\n<p>Con la participaci\u00f3n de m\u00e1s de 10 ni\u00f1os y ni\u00f1as entre los 11 y los 13 a\u00f1os de edad se lleno la ma\u00f1ana de la plaza principal de Puerto Colombia, desde las 8 AM hasta el medio d\u00eda todos se sumergieron en sus obras art\u00edsticas, generando una variedad de creaciones que reflejan el gran potencial art\u00edstico del municipio.<\/p>\n<p>&nbsp;<\/p>\n<p>En esta ocasi\u00f3n, Alex Mart\u00ednez, alumno de sexto grado del colegio UPA fue quien se llevo el primer puesto. \u00a0Su obra, para quienes los jurados, fue una de las m\u00e1s originales gracias a los buenos trazos que manej\u00f3 y sobre todo a la singularidad del mensaje que quizo expresar al no fijarse de ning\u00fan otro material sino el de su cabeza; ha sido escogida para representar al municipio en la decisi\u00f3n que se tomar\u00e1 a nivel regional para luego pasar a \u00a0la etapa nacional e internacional.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-3461 alignright\" src=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1977-300x200.jpg\" alt=\"Daniela Isabel Corpas Pe\u00f1uela.\" width=\"300\" height=\"200\" \/><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: left;\">Por su parte, la alumna del colegio Pies Descalzos Daniela Isabel Corpas Pe\u00f1uela, \u00a0a quien le hacemos un\u00a0reconocimiento especial, se lucio frente a todo el personal con una obra llena de personajes hist\u00f3ricos, figuras aleg\u00f3ricas y colores llenos de magia referentes al tema de la paz.<\/p>\n<p style=\"text-align: left;\">Felicitamos a todas y todos los que participaron en esta versi\u00f3n, esperando se preparen con todo su talento para el pr\u00f3ximo a\u00f1o.<\/p>\n<p><a href=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1939.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-3458 alignleft\" src=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1939-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1939-200x300.jpg 200w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1939-100x150.jpg 100w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1939.jpg 394w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; El pasado viernes 16 de Octubre se celebr\u00f3 en las instalaciones de la Fundaci\u00f3n Puerto Colombia el Concurso Internacional\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/ganador-concurso-internacional-cartel-de-la-paz\/\">Seguir Leyendo<\/a><\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3456","post","type-post","status-publish","format-standard","hentry","category-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ganador Concurso Internacional Cartel de la paz. - Fundaci\u00f3n Puerto Colombia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/ganador-concurso-internacional-cartel-de-la-paz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ganador Concurso Internacional Cartel de la paz.\" \/>\n<meta property=\"og:description\" content=\"&nbsp; El pasado viernes 16 de Octubre se celebr\u00f3 en las instalaciones de la Fundaci\u00f3n Puerto Colombia el Concurso Internacional\u2026 Seguir Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionpuertocolombia.org\/en\/ganador-concurso-internacional-cartel-de-la-paz\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Puerto Colombia\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-19T16:08:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-10-19T17:01:26+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Ganador Concurso Internacional Cartel de la paz.\",\"datePublished\":\"2015-10-19T16:08:41+00:00\",\"dateModified\":\"2015-10-19T17:01:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/\"},\"wordCount\":359,\"image\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/IMG_1962.jpg\",\"articleSection\":[\"Prensa\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/\",\"name\":\"Ganador Concurso Internacional Cartel de la paz. - Fundaci\u00f3n Puerto Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/IMG_1962.jpg\",\"datePublished\":\"2015-10-19T16:08:41+00:00\",\"dateModified\":\"2015-10-19T17:01:26+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/#primaryimage\",\"url\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/IMG_1962.jpg\",\"contentUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/IMG_1962.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/ganador-concurso-internacional-cartel-de-la-paz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ganador Concurso Internacional Cartel de la paz.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\",\"name\":\"Fundaci\u00f3n Puerto Colombia\",\"description\":\"Tierra Firme Para La Cultura!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ganador Concurso Internacional Cartel de la paz. - Fundaci\u00f3n Puerto Colombia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionpuertocolombia.org\/en\/ganador-concurso-internacional-cartel-de-la-paz\/","og_locale":"en_US","og_type":"article","og_title":"Ganador Concurso Internacional Cartel de la paz.","og_description":"&nbsp; El pasado viernes 16 de Octubre se celebr\u00f3 en las instalaciones de la Fundaci\u00f3n Puerto Colombia el Concurso Internacional\u2026 Seguir Leyendo","og_url":"https:\/\/fundacionpuertocolombia.org\/en\/ganador-concurso-internacional-cartel-de-la-paz\/","og_site_name":"Fundaci\u00f3n Puerto Colombia","article_published_time":"2015-10-19T16:08:41+00:00","article_modified_time":"2015-10-19T17:01:26+00:00","og_image":[{"url":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/#article","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/"},"author":{"name":"","@id":""},"headline":"Ganador Concurso Internacional Cartel de la paz.","datePublished":"2015-10-19T16:08:41+00:00","dateModified":"2015-10-19T17:01:26+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/"},"wordCount":359,"image":{"@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/#primaryimage"},"thumbnailUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962.jpg","articleSection":["Prensa"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/","url":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/","name":"Ganador Concurso Internacional Cartel de la paz. - Fundaci\u00f3n Puerto Colombia","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/#primaryimage"},"image":{"@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/#primaryimage"},"thumbnailUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962.jpg","datePublished":"2015-10-19T16:08:41+00:00","dateModified":"2015-10-19T17:01:26+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/#primaryimage","url":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962.jpg","contentUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2015\/10\/IMG_1962.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionpuertocolombia.org\/ganador-concurso-internacional-cartel-de-la-paz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionpuertocolombia.org\/"},{"@type":"ListItem","position":2,"name":"Ganador Concurso Internacional Cartel de la paz."}]},{"@type":"WebSite","@id":"https:\/\/fundacionpuertocolombia.org\/#website","url":"https:\/\/fundacionpuertocolombia.org\/","name":"Fundaci\u00f3n Puerto Colombia","description":"Tierra Firme Para La Cultura!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionpuertocolombia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/fundacionpuertocolombia.org\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/3456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/comments?post=3456"}],"version-history":[{"count":0,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/3456\/revisions"}],"wp:attachment":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/media?parent=3456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/categories?post=3456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/tags?post=3456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}