{"id":513,"date":"2014-04-05T16:02:31","date_gmt":"2014-04-05T16:02:31","guid":{"rendered":"http:\/\/fundacionpuertocolombia.org\/?p=513"},"modified":"2014-04-05T16:02:31","modified_gmt":"2014-04-05T16:02:31","slug":"agenda-cultural-del-08-al-12-de-abril","status":"publish","type":"post","link":"https:\/\/fundacionpuertocolombia.org\/en\/agenda-cultural-del-08-al-12-de-abril\/","title":{"rendered":"Agenda Cultural del 08 al 12 de Abril"},"content":{"rendered":"<p><a href=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-514\" alt=\"Agenda Cultural FPC abril 2da semana\" src=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg\" width=\"300\" height=\"253\" srcset=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg 300w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-1024x863.jpg 1024w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-177x150.jpg 177w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-150x126.jpg 150w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana.jpg 1067w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Puerto Colombia, abril 05 de 2014<\/p>\n<p>Del 08 al 12 de abril el cine, la literatura y las artes pl\u00e1sticas, tendr\u00e1n lugar esta semana en la Estaci\u00f3n Ferrocarril, gracias a las iniciativas culturales que la FUNDACI\u00d3N PUERTO COLOMBIA ha preparado para todos los habitantes y turistas del municipio.<\/p>\n<p><!--more--><\/p>\n<p><strong>Martes 08 de Abril<\/strong><br \/>\n<strong>CINE A LA PLAZA: &#8220;SOUNDS OF SAI&#8221;. Dir: Marcia Juzga\/2013\/ 35 min<\/strong><br \/>\n<strong>7:00 P.M. &#8211; Plaza Principal<\/strong><\/p>\n<p>SOUNDS OF SAI (Sonidos Sanandresanos), nos cuenta la aventura de los m\u00fasicos hijos de ese nuevo sonido, quienes buscan consolidar y conservar las ra\u00edces musicales de la isla, tendiendo como reto incursionar en la dif\u00edcil industria musical contempor\u00e1nea. Siglos de mestizaje y una historia profundamente ligada al m\u00fasica tradicional antillana, hacen de San Andr\u00e9s y Providencia un lugar m\u00e1gico en el que retumban sonidos que han crecido y se han alimentado de las nuevas tecnolog\u00edas y la globalizaci\u00f3n; una uni\u00f3n cultural que da a luz al sonido contempor\u00e1neo sanandresano desde la d\u00e9cada de los 80. La entrada es libre.<\/p>\n<p>Sobre la directora: Directora y realizadora audiovisual, egresada de la carrera de cine y fotograf\u00eda de Unitec, tambi\u00e9n realiz\u00f3 cursos de direcci\u00f3n de fotograf\u00eda y documental en La Habana, Cuba. Entre 2000 y 2004 se desempe\u00f1o en Los \u00c1ngeles, California como productora ejecutiva de Utop\u00eda Films y Ofrenda Films, entre 2004 y 2006, decide entrar a dirigir realities para la televisi\u00f3n Hispana de Los \u00c1ngeles y Houston. En la actualidad vive en Bogot\u00e1, Colombia; pa\u00eds en el que se ha desempe\u00f1ado como realizadora audiovisual e investigadora del \u00e1rea documental en diferentes productoras de televisi\u00f3n, participando as\u00ed en producciones nacionales e internacionales.<\/p>\n<p>Cine a la Plaza es organizado por la Fundaci\u00f3n Puerto Colombia, con el apoyo de la Fundaci\u00f3n MujerEs Audiovisual y el Ministerio de Cultura.<\/p>\n<p><strong>Jueves 10 de Abril<\/strong><br \/>\n<strong>CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero. <\/strong><br \/>\n<strong>Ciclo: &#8220;La Ni\u00f1ez en Tiempos de Guerra&#8221;.<\/strong><br \/>\n<strong>7:00 P.M. &#8211; Estaci\u00f3n Ferrocarril<\/strong><\/p>\n<p>Alemania, a\u00f1o cero (Germania, anno zero) es una pel\u00edcula neorrealista de Roberto Rossellini rodada en Berl\u00edn y estrenada en 1948. Esta obra completa la trilog\u00eda del director sobre la posguerra, a la que pertenecen tambi\u00e9n Roma, ciudad abierta y Camarada, aunque estos fueron rodados en Italia. La pel\u00edcula explora la herida dejada por el nazismo, que afect\u00f3 de forma terrible y profundo a una generaci\u00f3n simbolizada por el protagonista. La cinta hace parte del ciclo &#8220;La Ni\u00f1ez en Tiempos de guerra&#8221;. Entrada libre.<\/p>\n<p>Cine Foro &#8220;La Estaci\u00f3n&#8221; es organizado por la Fundaci\u00f3n Puerto Colombia, bajo la coordinaci\u00f3n de Germain Sclafer y el apoyo del Ministerio de Cultura.<\/p>\n<p><strong>Viernes 11 de Abril<\/strong><br \/>\n<strong>ASAMBLEA PREPARATORIA PARLAMENTO NACIONAL DE ESCRITORES<\/strong><br \/>\n<strong>10:00 A.M. &#8211; Estaci\u00f3n Ferrocarril<\/strong><\/p>\n<p>Con motivo de realizar la segunda Asamblea Preparatoria del Parlamento Nacional de Escritores, se dar\u00e1n cita este 11 de Abril el presidente, escritor Joce Daniels, y los coordinadores, para informar acerca del evento considerado el m\u00e1s importante en el campo acad\u00e9mico literario del Caribe Colombiano. Los temas a tratar ser\u00e1n: Conversar sobre la obra de la escritora, Marvel Luz Moreno Abello; Estimular la lectura entre profesionales, estudiantes, docentes y escritores regionales; y Proponer el nombre de un escritor barranquillero para rendirle homenaje en el Parlamento 2015.<\/p>\n<p>Coordina el evento en Puerto Colombia la poeta: Astrid Sof\u00eda Pedraza De la Hoz. Apoya: Fundaci\u00f3n Puerto Colombia y Centro Cultural Cayena de la Universidad del Norte.<\/p>\n<p><strong>S\u00e1bado 12 de Abril<\/strong><br \/>\n<strong>EXPOSICI\u00d3N COLECTIVA<\/strong><br \/>\n<strong>Puerto Colombia &#8220;Reserva Natural&#8221;<\/strong><br \/>\n<strong>En el marco de la celebraci\u00f3n del D\u00eda de la Tierra.<\/strong><br \/>\n<strong>4:00 P.M. &#8211; Estaci\u00f3n Ferrocarril<\/strong><\/p>\n<p>Puerto Colombia &#8220;Reserva Natural&#8221; es una exposici\u00f3n colectiva que agrupa la muestra fotogr\u00e1fica &#8220;Una mirada a nuestro terru\u00f1o&#8221; del fot\u00f3grafo, Jorge Contreras Lazzo; y la serie &#8220;Huellas de la Pacha Mama&#8221;, esculturas de madera fosilizada de Gustavo S\u00e1nchez Burgos.<\/p>\n<p>El objetivo de esta muestra, que va hasta el 14 de mayo, es mantener el cuidado de los recursos naturales con los que cuenta el municipio. Por eso la FUNDACI\u00d3N PUERTO COLOMBIA ha invitado a estos dos artistas residentes de la poblaci\u00f3n con sentido ambiental, para que a trav\u00e9s de sus obras nos recuerden mantener paz y armon\u00eda con la naturaleza, la tierra y el agua; recursos que escasean cada vez m\u00e1s debido a la indiferencia del ser humano hacia su h\u00e1bitat.<\/p>\n<p>La inauguraci\u00f3n es el s\u00e1bado 12 de abril a las 4:00 p.m. en la Estaci\u00f3n Ferrocarril.<\/p>\n<p>Todos los eventos son con entrada libre y gratuita. Cuentan con el respaldo institucional de la Gobernaci\u00f3n del Atl\u00e1ntico y el Ministerio de Cultura.<\/p>\n<p>Cordialmente,<\/p>\n<p>Carlos Mario Caselles<br \/>\nComunicaciones Fundaci\u00f3n Puerto Colombia<\/p>","protected":false},"excerpt":{"rendered":"<p>Puerto Colombia, abril 05 de 2014 Del 08 al 12 de abril el cine, la literatura y las artes pl\u00e1sticas,\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/agenda-cultural-del-08-al-12-de-abril\/\">Seguir Leyendo<\/a><\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[95,39,93,44,43,46,47,33,3,19,4,94,96],"class_list":["post-513","post","type-post","status-publish","format-standard","hentry","category-prensa","tag-asamblea-de-escritores","tag-ciclo-de-cine","tag-cine-a-la-plaza","tag-cine-en-puerto-colombia","tag-cine-foro","tag-cine-foro-la-estacion","tag-cine-gratis","tag-estacion-ferrocarril","tag-fundacion-puerto-colombia","tag-fundacionpuerto-colombia","tag-fundacionpuertocolombia","tag-parlamento-de-escritores","tag-parlamento-nacional-de-escritores"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Agenda Cultural del 08 al 12 de Abril - Fundaci\u00f3n Puerto Colombia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/agenda-cultural-del-08-al-12-de-abril\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda Cultural del 08 al 12 de Abril\" \/>\n<meta property=\"og:description\" content=\"Puerto Colombia, abril 05 de 2014 Del 08 al 12 de abril el cine, la literatura y las artes pl\u00e1sticas,\u2026 Seguir Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionpuertocolombia.org\/en\/agenda-cultural-del-08-al-12-de-abril\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Puerto Colombia\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-05T16:02:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Agenda Cultural del 08 al 12 de Abril\",\"datePublished\":\"2014-04-05T16:02:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/\"},\"wordCount\":805,\"image\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg\",\"keywords\":[\"asamblea de escritores\",\"ciclo de cine\",\"cine a la plaza\",\"cine en puerto colombia\",\"Cine Foro\",\"cine foro la estaci\u00f3n\",\"cine gratis\",\"Estaci\u00f3n Ferrocarril\",\"fundaci\u00f3n puerto colombia\",\"fundacionpuerto colombia\",\"fundacionpuertocolombia\",\"parlamento de escritores\",\"parlamento nacional de escritores\"],\"articleSection\":[\"Prensa\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/\",\"name\":\"Agenda Cultural del 08 al 12 de Abril - Fundaci\u00f3n Puerto Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg\",\"datePublished\":\"2014-04-05T16:02:31+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/#primaryimage\",\"url\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg\",\"contentUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-cultural-del-08-al-12-de-abril\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda Cultural del 08 al 12 de Abril\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\",\"name\":\"Fundaci\u00f3n Puerto Colombia\",\"description\":\"Tierra Firme Para La Cultura!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Agenda Cultural del 08 al 12 de Abril - Fundaci\u00f3n Puerto Colombia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionpuertocolombia.org\/en\/agenda-cultural-del-08-al-12-de-abril\/","og_locale":"en_US","og_type":"article","og_title":"Agenda Cultural del 08 al 12 de Abril","og_description":"Puerto Colombia, abril 05 de 2014 Del 08 al 12 de abril el cine, la literatura y las artes pl\u00e1sticas,\u2026 Seguir Leyendo","og_url":"https:\/\/fundacionpuertocolombia.org\/en\/agenda-cultural-del-08-al-12-de-abril\/","og_site_name":"Fundaci\u00f3n Puerto Colombia","article_published_time":"2014-04-05T16:02:31+00:00","og_image":[{"url":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/#article","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/"},"author":{"name":"","@id":""},"headline":"Agenda Cultural del 08 al 12 de Abril","datePublished":"2014-04-05T16:02:31+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/"},"wordCount":805,"image":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/#primaryimage"},"thumbnailUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg","keywords":["asamblea de escritores","ciclo de cine","cine a la plaza","cine en puerto colombia","Cine Foro","cine foro la estaci\u00f3n","cine gratis","Estaci\u00f3n Ferrocarril","fundaci\u00f3n puerto colombia","fundacionpuerto colombia","fundacionpuertocolombia","parlamento de escritores","parlamento nacional de escritores"],"articleSection":["Prensa"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/","url":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/","name":"Agenda Cultural del 08 al 12 de Abril - Fundaci\u00f3n Puerto Colombia","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/#primaryimage"},"image":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/#primaryimage"},"thumbnailUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg","datePublished":"2014-04-05T16:02:31+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/#primaryimage","url":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg","contentUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-abril-2da-semana-300x253.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionpuertocolombia.org\/agenda-cultural-del-08-al-12-de-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionpuertocolombia.org\/"},{"@type":"ListItem","position":2,"name":"Agenda Cultural del 08 al 12 de Abril"}]},{"@type":"WebSite","@id":"https:\/\/fundacionpuertocolombia.org\/#website","url":"https:\/\/fundacionpuertocolombia.org\/","name":"Fundaci\u00f3n Puerto Colombia","description":"Tierra Firme Para La Cultura!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionpuertocolombia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/fundacionpuertocolombia.org\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/comments?post=513"}],"version-history":[{"count":0,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/513\/revisions"}],"wp:attachment":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/media?parent=513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/categories?post=513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/tags?post=513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}