{"id":516,"date":"2014-04-07T22:54:37","date_gmt":"2014-04-07T22:54:37","guid":{"rendered":"http:\/\/fundacionpuertocolombia.org\/?p=516"},"modified":"2014-04-07T22:54:37","modified_gmt":"2014-04-07T22:54:37","slug":"cine-foro-la-estacion-alemania-ano-cero","status":"publish","type":"post","link":"https:\/\/fundacionpuertocolombia.org\/en\/cine-foro-la-estacion-alemania-ano-cero\/","title":{"rendered":"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero"},"content":{"rendered":"<p><strong><a href=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/03\/2-Alemania-A\u00f1o-cero.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-497\" alt=\"2 Alemania A\u00f1o cero\" src=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/03\/2-Alemania-A\u00f1o-cero-222x300.jpg\" width=\"222\" height=\"300\" srcset=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/03\/2-Alemania-A\u00f1o-cero-222x300.jpg 222w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/03\/2-Alemania-A\u00f1o-cero-111x150.jpg 111w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/03\/2-Alemania-A\u00f1o-cero.jpg 667w\" sizes=\"(max-width: 222px) 100vw, 222px\" \/><\/a>Alemania, a\u00f1o cero<\/strong> (Germania, anno zero) es una pel\u00edcula neorrealista de Roberto Rossellini rodada en Berl\u00edn y estrenada en 1948. Esta obra completa la trilog\u00eda del director sobre la posguerra, a la que pertenecen tambi\u00e9n Roma, ciudad abierta y Camarada, aunque estos fueron rodados en Italia. La pel\u00edcula explora la herida dejada por el nazismo, que afect\u00f3 de forma terrible y profundo a una generaci\u00f3n simbolizada por el protagonista. La cinta hace parte del ciclo &#8220;La Ni\u00f1ez en Tiempos de guerra&#8221;. Entrada libre.<\/p>\n<p>Cine Foro &#8220;La Estaci\u00f3n&#8221; es organizado por la Fundaci\u00f3n Puerto Colombia, bajo la coordinaci\u00f3n de Germain Sclafer; con el apoyo del Ministerio de Cultura y la Secretar\u00eda de Cultura y Patrimonio de la Gobernaci\u00f3n del Atl\u00e1ntico.<\/p>","protected":false},"excerpt":{"rendered":"<p>Alemania, a\u00f1o cero (Germania, anno zero) es una pel\u00edcula neorrealista de Roberto Rossellini rodada en Berl\u00edn y estrenada en 1948.\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/cine-foro-la-estacion-alemania-ano-cero\/\">Seguir Leyendo<\/a><\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[39,44,43,46,47,33,3,19,4],"class_list":["post-516","post","type-post","status-publish","format-standard","hentry","category-prensa","tag-ciclo-de-cine","tag-cine-en-puerto-colombia","tag-cine-foro","tag-cine-foro-la-estacion","tag-cine-gratis","tag-estacion-ferrocarril","tag-fundacion-puerto-colombia","tag-fundacionpuerto-colombia","tag-fundacionpuertocolombia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero - Fundaci\u00f3n Puerto Colombia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/cine-foro-la-estacion-alemania-ano-cero\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero\" \/>\n<meta property=\"og:description\" content=\"Alemania, a\u00f1o cero (Germania, anno zero) es una pel\u00edcula neorrealista de Roberto Rossellini rodada en Berl\u00edn y estrenada en 1948.\u2026 Seguir Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionpuertocolombia.org\/en\/cine-foro-la-estacion-alemania-ano-cero\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Puerto Colombia\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-07T22:54:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/cine-foro-la-estacion-alemania-ano-cero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/cine-foro-la-estacion-alemania-ano-cero\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero\",\"datePublished\":\"2014-04-07T22:54:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/cine-foro-la-estacion-alemania-ano-cero\\\/\"},\"wordCount\":141,\"keywords\":[\"ciclo de cine\",\"cine en puerto colombia\",\"Cine Foro\",\"cine foro la estaci\u00f3n\",\"cine gratis\",\"Estaci\u00f3n Ferrocarril\",\"fundaci\u00f3n puerto colombia\",\"fundacionpuerto colombia\",\"fundacionpuertocolombia\"],\"articleSection\":[\"Prensa\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/cine-foro-la-estacion-alemania-ano-cero\\\/\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/cine-foro-la-estacion-alemania-ano-cero\\\/\",\"name\":\"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero - Fundaci\u00f3n Puerto Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\"},\"datePublished\":\"2014-04-07T22:54:37+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/cine-foro-la-estacion-alemania-ano-cero\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionpuertocolombia.org\\\/cine-foro-la-estacion-alemania-ano-cero\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/cine-foro-la-estacion-alemania-ano-cero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\",\"name\":\"Fundaci\u00f3n Puerto Colombia\",\"description\":\"Tierra Firme Para La Cultura!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero - Fundaci\u00f3n Puerto Colombia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionpuertocolombia.org\/en\/cine-foro-la-estacion-alemania-ano-cero\/","og_locale":"en_US","og_type":"article","og_title":"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero","og_description":"Alemania, a\u00f1o cero (Germania, anno zero) es una pel\u00edcula neorrealista de Roberto Rossellini rodada en Berl\u00edn y estrenada en 1948.\u2026 Seguir Leyendo","og_url":"https:\/\/fundacionpuertocolombia.org\/en\/cine-foro-la-estacion-alemania-ano-cero\/","og_site_name":"Fundaci\u00f3n Puerto Colombia","article_published_time":"2014-04-07T22:54:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionpuertocolombia.org\/cine-foro-la-estacion-alemania-ano-cero\/#article","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/cine-foro-la-estacion-alemania-ano-cero\/"},"author":{"name":"","@id":""},"headline":"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero","datePublished":"2014-04-07T22:54:37+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/cine-foro-la-estacion-alemania-ano-cero\/"},"wordCount":141,"keywords":["ciclo de cine","cine en puerto colombia","Cine Foro","cine foro la estaci\u00f3n","cine gratis","Estaci\u00f3n Ferrocarril","fundaci\u00f3n puerto colombia","fundacionpuerto colombia","fundacionpuertocolombia"],"articleSection":["Prensa"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/fundacionpuertocolombia.org\/cine-foro-la-estacion-alemania-ano-cero\/","url":"https:\/\/fundacionpuertocolombia.org\/cine-foro-la-estacion-alemania-ano-cero\/","name":"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero - Fundaci\u00f3n Puerto Colombia","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/#website"},"datePublished":"2014-04-07T22:54:37+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/fundacionpuertocolombia.org\/cine-foro-la-estacion-alemania-ano-cero\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionpuertocolombia.org\/cine-foro-la-estacion-alemania-ano-cero\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionpuertocolombia.org\/cine-foro-la-estacion-alemania-ano-cero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionpuertocolombia.org\/"},{"@type":"ListItem","position":2,"name":"CINE FORO LA ESTACI\u00d3N: Alemania, A\u00f1o Cero"}]},{"@type":"WebSite","@id":"https:\/\/fundacionpuertocolombia.org\/#website","url":"https:\/\/fundacionpuertocolombia.org\/","name":"Fundaci\u00f3n Puerto Colombia","description":"Tierra Firme Para La Cultura!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionpuertocolombia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/fundacionpuertocolombia.org\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/comments?post=516"}],"version-history":[{"count":0,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/516\/revisions"}],"wp:attachment":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/media?parent=516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/categories?post=516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/tags?post=516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}