{"id":525,"date":"2014-04-13T18:18:31","date_gmt":"2014-04-13T18:18:31","guid":{"rendered":"http:\/\/fundacionpuertocolombia.org\/?p=525"},"modified":"2014-04-13T18:18:31","modified_gmt":"2014-04-13T18:18:31","slug":"agenda-semana-santa-14-al-20-de-abril","status":"publish","type":"post","link":"https:\/\/fundacionpuertocolombia.org\/en\/agenda-semana-santa-14-al-20-de-abril\/","title":{"rendered":"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL"},"content":{"rendered":"<p><a href=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-526\" alt=\"Agenda Cultural FPC Semana Santa\" src=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg\" width=\"300\" height=\"251\" srcset=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg 300w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-1024x858.jpg 1024w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-178x150.jpg 178w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-150x125.jpg 150w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa.jpg 1073w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>La FUNDACI\u00d3N PUERTO COLOMBIA, en alianza con otras entidades y grupos de artistas, ha organizado una atractiva programaci\u00f3n para toda la familia durante la Semana Santa. Espacio de reflexi\u00f3n, pero tambi\u00e9n de integraci\u00f3n entre j\u00f3venes, ni\u00f1os y adultos. A continuaci\u00f3n la agenda de la Semana Mayor:<!--more--><\/p>\n<p><strong>MARTES 15 DE ABRIL<\/strong><br \/>\nCINE A LA PLAZA:<br \/>\nSinfon\u00eda de Mercado. Helena Salguero &#8211; Jimena Prieto \/ 2012 \/ 27 min.<br \/>\nProyecci\u00f3n de documentales colombianos.<br \/>\n7:00 P.M. \/ Plaza Principal de Puerto Colombia<\/p>\n<p>Sinfon\u00eda de Mercado es un documental musical que muestra un retrato del centro de acopio de productos m\u00e1s grande de Colombia, llamado Corabastos. A trav\u00e9s de un estilo po\u00e9tico, se propone una mirada distinta a la que conciben muchos ciudadanos en Bogot\u00e1, exaltando los r\u00edmos, los colores, las texturas, las personas y los oficios que se pueden apreciar a lo largo de una jornada laboral en este lugar.<\/p>\n<p>Cine a la Plaza se hace desde el 1 de abril, con el objetivo de acercar a la comunidad, transe\u00fantes y p\u00fablico en general con el cine nacional, en un entorno abierto, gratuito y al aire libre. Cuenta con el respaldo de la Fundaci\u00f3n MujerEs Audiovisual y Proim\u00e1genes Colombia.<\/p>\n<p><strong>JUEVES SANTO 17 DE ABRIL<\/strong><br \/>\nCINE FORO LA ESTACI\u00d3N:<br \/>\nLos Colores de la Monta\u00f1a. Carlos Cesar Arbel\u00e1ez \/ 2011 \/ 90 min.<br \/>\nCiclo: \u201cLa Ni\u00f1ez en Tiempos de Guerra\u201d.<br \/>\n7:00 P.M. \/ Estaci\u00f3n Ferrocarril de Bol\u00edvar<\/p>\n<p>El ciclo de pel\u00edculas sobre ni\u00f1os en medio de la guerra, presenta este jueves santo 17 de abril la pel\u00edcula colombiana Los Colores de la Monta\u00f1a. La historia se basa en la vida de Manuel y sus amigos de escuela, quien tiene una vieja pelota con la que juega al f\u00fatbol todos los d\u00edas en el campo. Sue\u00f1a con llegar a ser un gran arquero de f\u00fatbol y el sue\u00f1o parece que se cumple cuando, Ernesto, su padre, le regala un bal\u00f3n nuevo. Pero un accidente inesperado hace que el bal\u00f3n caiga en un campo minado. A pesar del peligro, Manuel decide no abandonar su bal\u00f3n\u2026 Convence a Juli\u00e1n y a Poca Luz, sus dos mejores amigos, para que juntos lo rescaten. En medio de las aventuras y los juegos infantiles, los signos de un conflicto armado empiezan a aparecer en la vida de los habitantes de la vereda La Pradera. Una excelente pel\u00edcula que habla de la realidad de millones de colombianos que han sufrido un conflicto interno desde 1948, dando como resultado ser el segundo pa\u00eds en el mundo con mayor tasa de desplazamientos forzados.<\/p>\n<p>El Cine Foro La Estaci\u00f3n es organizado por la Fundaci\u00f3n Puerto Colombia, con la coordinaci\u00f3n del periodista y cr\u00edtico de cine, Germain Sclafer. Cuenta con el respaldo del Ministerio de Cultura y la Secretar\u00eda de Cultura y Patrimonio de la Gobernaci\u00f3n del Atl\u00e1ntico.<\/p>\n<p><strong>S\u00c1BADO 19 y DOMINGO 20 DE ABRIL<\/strong><br \/>\nFERIA ARTESANAL AL PUERTO<br \/>\n10:00 A.M. \/ Plaza Principal de Puerto Colombia<\/p>\n<p>Piezas en madera, semillas, fibras de vidrio, resina, tejidos, entre otras t\u00e9cnicas estar\u00e1n exhibi\u00e9ndose en los alrededores de la plaza principal y la Estaci\u00f3n del Ferrocarril los dos \u00faltimos d\u00edas del la Semana Santa con la gran Feria Artesanal al Puerto. Esta iniciativa, apoyada por la FUNDACI\u00d3N PUERTO COLOMBIA, se hace con el fin de articular la gran oferta artesanal y gastron\u00f3mica del municipio durante los d\u00edas de la semana santa. En ella el p\u00fablico residente y el que nos visita, podr\u00e1 llevar a sus hogares productos 100% hechos en Puerto Colombia.<\/p>\n<p>Basados en que el municipio cuenta con una poblaci\u00f3n de artistas pl\u00e1sticos que representa el 21,24% en el Atl\u00e1ntico, y 2,78% en artesanos, seg\u00fan cifras del directorio de artistas visuales y artesanos del departamento; se busca incrementar ambas cifras, ya que es posible que muchos no han sido identificados y la Feria Artesanal, servir\u00e1 para dar plataforma a su talento y mejorar sus ingresos.<\/p>\n<p>Los horarios de la Feria Artesanal al Puerto ser\u00e1n de 10:00 a.m. a 6:00 p.m. con entrada libre y gratuita. Para mayores comunicarse con la coordinadora de la feria, Paola Eljach al celular 3046783970.<\/p>\n<p><strong>TODA LA SEMANA<\/strong><br \/>\nExposici\u00f3n Colectiva:<br \/>\nPuerto Colombia \u201cReserva Natural\u201d<br \/>\nCelebrando el D\u00eda de la Tierra.<br \/>\n8:30 a.m. a 12:30 y 3:00 p.m. a 6:00 p.m. \/ Estaci\u00f3n Ferrocarril de Bol\u00edvar<\/p>\n<p>Puerto Colombia &#8220;Reserva Natural&#8221; es una exposici\u00f3n colectiva que agrupa la muestra fotogr\u00e1fica &#8220;Una mirada a nuestro terru\u00f1o&#8221; del fot\u00f3grafo, Jorge Contreras Lazzo; y la serie &#8220;Huellas de la Pacha Mama&#8221;, esculturas de madera fosilizada de Gustavo S\u00e1nchez Burgos.<\/p>\n<p>El objetivo de esta muestra, que va hasta el 14 de mayo, es mantener el cuidado de los recursos naturales con los que cuenta el municipio. Por eso la FUNDACI\u00d3N PUERTO COLOMBIA ha invitado a estos dos artistas residentes de la poblaci\u00f3n con sentido ambiental, para que a trav\u00e9s de sus obras nos recuerden mantener paz y armon\u00eda con la naturaleza, la tierra y el agua; recursos que escasean cada vez m\u00e1s debido a la indiferencia del ser humano hacia su h\u00e1bitat.<\/p>\n<p>La muestra estar\u00e1 abierta al p\u00fablico durante la Semana Santa en los horarios de Lunes a Mi\u00e9rcoles de 8:30 a.m. a 12:30 y 3:00 p.m. a 6:00 p.m. Jueves, Viernes, S\u00e1bado y Domingo de 3:00 p.m. a 6:00 p.m.<br \/>\nCordialmente,<\/p>\n<p>Carlos Mario Caselles<br \/>\nComunicaciones<br \/>\nFundaci\u00f3n Puerto Colombia<\/p>","protected":false},"excerpt":{"rendered":"<p>La FUNDACI\u00d3N PUERTO COLOMBIA, en alianza con otras entidades y grupos de artistas, ha organizado una atractiva programaci\u00f3n para toda\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/agenda-semana-santa-14-al-20-de-abril\/\">Seguir Leyendo<\/a><\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[99,60,39,93,44,43,46,47,33,98,3,19,4,100,6],"class_list":["post-525","post","type-post","status-publish","format-standard","hentry","category-prensa","tag-artesanos-de-puerto-colombia","tag-carlos-mario-caselles","tag-ciclo-de-cine","tag-cine-a-la-plaza","tag-cine-en-puerto-colombia","tag-cine-foro","tag-cine-foro-la-estacion","tag-cine-gratis","tag-estacion-ferrocarril","tag-feria-artesanal","tag-fundacion-puerto-colombia","tag-fundacionpuerto-colombia","tag-fundacionpuertocolombia","tag-los-colores-de-la-montana","tag-puerto-colombia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AGENDA SEMANA SANTA 14 AL 20 DE ABRIL - Fundaci\u00f3n Puerto Colombia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/agenda-semana-santa-14-al-20-de-abril\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL\" \/>\n<meta property=\"og:description\" content=\"La FUNDACI\u00d3N PUERTO COLOMBIA, en alianza con otras entidades y grupos de artistas, ha organizado una atractiva programaci\u00f3n para toda\u2026 Seguir Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionpuertocolombia.org\/en\/agenda-semana-santa-14-al-20-de-abril\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Puerto Colombia\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-13T18:18:31+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL\",\"datePublished\":\"2014-04-13T18:18:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/\"},\"wordCount\":930,\"image\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg\",\"keywords\":[\"artesanos de puerto colombia\",\"Carlos Mario Caselles\",\"ciclo de cine\",\"cine a la plaza\",\"cine en puerto colombia\",\"Cine Foro\",\"cine foro la estaci\u00f3n\",\"cine gratis\",\"Estaci\u00f3n Ferrocarril\",\"feria artesanal\",\"fundaci\u00f3n puerto colombia\",\"fundacionpuerto colombia\",\"fundacionpuertocolombia\",\"los colores de la monta\u00f1a\",\"puerto colombia\"],\"articleSection\":[\"Prensa\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/\",\"name\":\"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL - Fundaci\u00f3n Puerto Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg\",\"datePublished\":\"2014-04-13T18:18:31+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/#primaryimage\",\"url\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg\",\"contentUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/agenda-semana-santa-14-al-20-de-abril\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\",\"name\":\"Fundaci\u00f3n Puerto Colombia\",\"description\":\"Tierra Firme Para La Cultura!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL - Fundaci\u00f3n Puerto Colombia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionpuertocolombia.org\/en\/agenda-semana-santa-14-al-20-de-abril\/","og_locale":"en_US","og_type":"article","og_title":"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL","og_description":"La FUNDACI\u00d3N PUERTO COLOMBIA, en alianza con otras entidades y grupos de artistas, ha organizado una atractiva programaci\u00f3n para toda\u2026 Seguir Leyendo","og_url":"https:\/\/fundacionpuertocolombia.org\/en\/agenda-semana-santa-14-al-20-de-abril\/","og_site_name":"Fundaci\u00f3n Puerto Colombia","article_published_time":"2014-04-13T18:18:31+00:00","og_image":[{"url":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/#article","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/"},"author":{"name":"","@id":""},"headline":"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL","datePublished":"2014-04-13T18:18:31+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/"},"wordCount":930,"image":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/#primaryimage"},"thumbnailUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg","keywords":["artesanos de puerto colombia","Carlos Mario Caselles","ciclo de cine","cine a la plaza","cine en puerto colombia","Cine Foro","cine foro la estaci\u00f3n","cine gratis","Estaci\u00f3n Ferrocarril","feria artesanal","fundaci\u00f3n puerto colombia","fundacionpuerto colombia","fundacionpuertocolombia","los colores de la monta\u00f1a","puerto colombia"],"articleSection":["Prensa"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/","url":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/","name":"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL - Fundaci\u00f3n Puerto Colombia","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/#primaryimage"},"image":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/#primaryimage"},"thumbnailUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg","datePublished":"2014-04-13T18:18:31+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/#primaryimage","url":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg","contentUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/04\/Agenda-Cultural-FPC-Semana-Santa-300x251.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionpuertocolombia.org\/agenda-semana-santa-14-al-20-de-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionpuertocolombia.org\/"},{"@type":"ListItem","position":2,"name":"AGENDA SEMANA SANTA 14 AL 20 DE ABRIL"}]},{"@type":"WebSite","@id":"https:\/\/fundacionpuertocolombia.org\/#website","url":"https:\/\/fundacionpuertocolombia.org\/","name":"Fundaci\u00f3n Puerto Colombia","description":"Tierra Firme Para La Cultura!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionpuertocolombia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/fundacionpuertocolombia.org\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/comments?post=525"}],"version-history":[{"count":0,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/525\/revisions"}],"wp:attachment":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/media?parent=525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/categories?post=525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/tags?post=525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}