{"id":757,"date":"2014-06-20T21:35:48","date_gmt":"2014-06-20T21:35:48","guid":{"rendered":"http:\/\/fundacionpuertocolombia.org\/?p=757"},"modified":"2014-06-26T15:28:36","modified_gmt":"2014-06-26T15:28:36","slug":"taller-de-mosaicos-para-jovenes","status":"publish","type":"post","link":"https:\/\/fundacionpuertocolombia.org\/en\/taller-de-mosaicos-para-jovenes\/","title":{"rendered":"TALLER DE MOSAICOS PARA J\u00d3VENES"},"content":{"rendered":"<p><a href=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-758 size-large\" src=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-1024x770.jpg\" alt=\"taller de mosaicos\" width=\"800\" height=\"601\" srcset=\"https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-1024x770.jpg 1024w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-300x225.jpg 300w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-199x150.jpg 199w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-150x112.jpg 150w, https:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos.jpg 1196w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><strong>FUNDACI\u00d3N PUERTO COLOMBIA ORGANIZA TALLER DE MOSAICO<\/strong><br \/>\nLa actividad forma parte del proyecto &#8220;Malec\u00f3n del Arte&#8221;.<\/p>\n<p>Puerto Colombia, junio 26 de 2013<\/p>\n<p>Con el fin de seguir en la l\u00ednea de unir los espacios tur\u00edsticos y culturales del municipio de Puerto Colombia con la poblaci\u00f3n, en el mes de julio durante la temporada vacacional, la Fundaci\u00f3n Puerto Colombia con el patrocinio de la Fundaci\u00f3n Gases del Caribe y la Fundaci\u00f3n Puerto de Barranquilla, ha organizado un taller de mosaicos dirigido por la ceramista Chelo Rodr\u00edguez, para j\u00f3venes residentes del municipio entre los 15 a 25 a\u00f1os.<!--more--><\/p>\n<p>A trav\u00e9s de este curso se pretende hacer mas participativa a la comunidad de futuros artistas, con un ejercicio de arte en el espacio p\u00fablico con la intervenci\u00f3n de las barandas de los puentes del malec\u00f3n. Con ello se podr\u00e1 generar sentido de pertenencia, capacitar a los j\u00f3venes en el arte del dise\u00f1o y aplicaci\u00f3n del mosaico, obteniendo beneficios a futuro hacia ellos y la poblaci\u00f3n.<\/p>\n<p>&#8220;Esta iniciativa se fundamenta en el ejercicio de mantenimiento y durabilidad de las obras que se ejecutaron durante el proyecto AGUA AIRE ARTE, 80 Artistas en el Malec\u00f3n, proyecto realizado en alianza con la Alcald\u00eda Municipal de Puerto Colombia y la Fundaci\u00f3n Triple A; en el cual observamos que las bancas ejecutadas con esta t\u00e9cnica son el ideal para los trabajos en el medio en que se encuentran por su resistencia y durabilidad&#8221;, informa la Presidenta de la Fundaci\u00f3n Puerto Colombia, Hortensia S\u00e1nchez Pati\u00f1o.<\/p>\n<p>La duraci\u00f3n del taller ser\u00e1n dos semanas en el mes de julio y los conocimientos se aplicar\u00e1n en la intervenci\u00f3n de las 2 barandas de los puentes del malec\u00f3n, con un dise\u00f1o planteado por los j\u00f3venes que tomen el curso, guiados por la tutora.<\/p>\n<p>Las inscripciones est\u00e1n abiertas con cupos limitados. El curso inicia el martes 1 de julio de 2014\u00a0a las 9:00 a.m.\u00a0Mayores informes en la Estaci\u00f3n Ferrocarril de Bol\u00edvar, Plaza de Puerto Colombia (Atl\u00e1ntico) Tel\u00e9fonos:3096120 &#8211; 3104477916 \/ fundacionpuertocolombia@gmail.com<\/p>\n<p>T\u00e9cnica de Mosaico: Se le conoce a esta t\u00e9cnica como una obra pict\u00f3rica elaborada con peque\u00f1as piezas de piedra, cer\u00e1mica, vidrio u otros materiales similares de diversas formas y colores, llamadas teselas, unidas mediante yeso, u otro aglomerante, para formar composiciones decorativas geom\u00e9tricas o figurativas.<\/p>\n<p>Perfil de Chelo Rodr\u00edguez: Ceramista, Gerente y propietaria del taller de cer\u00e1mica \u201cChelo-Sop\u00f3-Colombia\u201d. Directora del proyecto \u201cMokan\u00e1 hoy, tesoros vivos\u201d recuperaci\u00f3n de la tradici\u00f3n alfarera de la cultura Mokan\u00e1 en el Departamento del Atl\u00e1ntico. Directora del proyecto &#8220;Bancarte&#8221; en Sop\u00f3-Cundinamarca. Autora de la banca &#8220;Un pedacito de mar&#8221; y la escultura &#8220;Anclados&#8221;, en el Malec\u00f3n del Arte de Puerto Colombia.<\/p>\n<p>Cordialmente,<\/p>\n<p>Carlos Mario Caselles<br \/>\nComunicaciones<br \/>\nFundaci\u00f3n Puerto Colombia<\/p>","protected":false},"excerpt":{"rendered":"<p>FUNDACI\u00d3N PUERTO COLOMBIA ORGANIZA TALLER DE MOSAICO La actividad forma parte del proyecto &#8220;Malec\u00f3n del Arte&#8221;. Puerto Colombia, junio 26\u2026 <a class=\"continue-reading-link\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/taller-de-mosaicos-para-jovenes\/\">Seguir Leyendo<\/a><\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[155,3,11,19,4,64,154,6,151,153,152],"class_list":["post-757","post","type-post","status-publish","format-standard","hentry","category-prensa","tag-actividades-jovenes-puerto-colombia","tag-fundacion-puerto-colombia","tag-fundacion-puertocolombia","tag-fundacionpuerto-colombia","tag-fundacionpuertocolombia","tag-malecon-del-arte","tag-mosaico-puerto-colombia","tag-puerto-colombia","tag-taller-de-mosaicos","tag-taller-en-puerto-colombia","tag-taller-para-jovenes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>TALLER DE MOSAICOS PARA J\u00d3VENES - Fundaci\u00f3n Puerto Colombia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundacionpuertocolombia.org\/en\/taller-de-mosaicos-para-jovenes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TALLER DE MOSAICOS PARA J\u00d3VENES\" \/>\n<meta property=\"og:description\" content=\"FUNDACI\u00d3N PUERTO COLOMBIA ORGANIZA TALLER DE MOSAICO La actividad forma parte del proyecto &#8220;Malec\u00f3n del Arte&#8221;. Puerto Colombia, junio 26\u2026 Seguir Leyendo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundacionpuertocolombia.org\/en\/taller-de-mosaicos-para-jovenes\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n Puerto Colombia\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-20T21:35:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-06-26T15:28:36+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-1024x770.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"TALLER DE MOSAICOS PARA J\u00d3VENES\",\"datePublished\":\"2014-06-20T21:35:48+00:00\",\"dateModified\":\"2014-06-26T15:28:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/\"},\"wordCount\":493,\"image\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/taller-de-mosaicos-1024x770.jpg\",\"keywords\":[\"actividades jovenes puerto colombia\",\"fundaci\u00f3n puerto colombia\",\"fundaci\u00f3n puertocolombia\",\"fundacionpuerto colombia\",\"fundacionpuertocolombia\",\"malec\u00f3n del arte\",\"mosaico puerto colombia\",\"puerto colombia\",\"TALLER DE MOSAICOS\",\"taller en puerto colombia\",\"taller para jovenes\"],\"articleSection\":[\"Prensa\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/\",\"name\":\"TALLER DE MOSAICOS PARA J\u00d3VENES - Fundaci\u00f3n Puerto Colombia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/taller-de-mosaicos-1024x770.jpg\",\"datePublished\":\"2014-06-20T21:35:48+00:00\",\"dateModified\":\"2014-06-26T15:28:36+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/#primaryimage\",\"url\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/taller-de-mosaicos-1024x770.jpg\",\"contentUrl\":\"http:\\\/\\\/fundacionpuertocolombia.org\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/taller-de-mosaicos-1024x770.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/taller-de-mosaicos-para-jovenes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TALLER DE MOSAICOS PARA J\u00d3VENES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/#website\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/\",\"name\":\"Fundaci\u00f3n Puerto Colombia\",\"description\":\"Tierra Firme Para La Cultura!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/fundacionpuertocolombia.org\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TALLER DE MOSAICOS PARA J\u00d3VENES - Fundaci\u00f3n Puerto Colombia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundacionpuertocolombia.org\/en\/taller-de-mosaicos-para-jovenes\/","og_locale":"en_US","og_type":"article","og_title":"TALLER DE MOSAICOS PARA J\u00d3VENES","og_description":"FUNDACI\u00d3N PUERTO COLOMBIA ORGANIZA TALLER DE MOSAICO La actividad forma parte del proyecto &#8220;Malec\u00f3n del Arte&#8221;. Puerto Colombia, junio 26\u2026 Seguir Leyendo","og_url":"https:\/\/fundacionpuertocolombia.org\/en\/taller-de-mosaicos-para-jovenes\/","og_site_name":"Fundaci\u00f3n Puerto Colombia","article_published_time":"2014-06-20T21:35:48+00:00","article_modified_time":"2014-06-26T15:28:36+00:00","og_image":[{"url":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-1024x770.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/#article","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/"},"author":{"name":"","@id":""},"headline":"TALLER DE MOSAICOS PARA J\u00d3VENES","datePublished":"2014-06-20T21:35:48+00:00","dateModified":"2014-06-26T15:28:36+00:00","mainEntityOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/"},"wordCount":493,"image":{"@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/#primaryimage"},"thumbnailUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-1024x770.jpg","keywords":["actividades jovenes puerto colombia","fundaci\u00f3n puerto colombia","fundaci\u00f3n puertocolombia","fundacionpuerto colombia","fundacionpuertocolombia","malec\u00f3n del arte","mosaico puerto colombia","puerto colombia","TALLER DE MOSAICOS","taller en puerto colombia","taller para jovenes"],"articleSection":["Prensa"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/","url":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/","name":"TALLER DE MOSAICOS PARA J\u00d3VENES - Fundaci\u00f3n Puerto Colombia","isPartOf":{"@id":"https:\/\/fundacionpuertocolombia.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/#primaryimage"},"image":{"@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/#primaryimage"},"thumbnailUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-1024x770.jpg","datePublished":"2014-06-20T21:35:48+00:00","dateModified":"2014-06-26T15:28:36+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/#primaryimage","url":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-1024x770.jpg","contentUrl":"http:\/\/fundacionpuertocolombia.org\/wp-content\/uploads\/2014\/06\/taller-de-mosaicos-1024x770.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fundacionpuertocolombia.org\/taller-de-mosaicos-para-jovenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/fundacionpuertocolombia.org\/"},{"@type":"ListItem","position":2,"name":"TALLER DE MOSAICOS PARA J\u00d3VENES"}]},{"@type":"WebSite","@id":"https:\/\/fundacionpuertocolombia.org\/#website","url":"https:\/\/fundacionpuertocolombia.org\/","name":"Fundaci\u00f3n Puerto Colombia","description":"Tierra Firme Para La Cultura!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundacionpuertocolombia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/fundacionpuertocolombia.org\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/comments?post=757"}],"version-history":[{"count":0,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/posts\/757\/revisions"}],"wp:attachment":[{"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/media?parent=757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/categories?post=757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fundacionpuertocolombia.org\/en\/wp-json\/wp\/v2\/tags?post=757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}